{"id":2709,"date":"2014-07-02T15:17:57","date_gmt":"2014-07-02T14:17:57","guid":{"rendered":"http:\/\/www.sidpa72.fr\/w\/portfolio-items\/paillasse-hospitaliere-5-2"},"modified":"2019-12-16T16:38:14","modified_gmt":"2019-12-16T15:38:14","slug":"paillasse-hospitaliere-5","status":"publish","type":"avada_portfolio","link":"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5","title":{"rendered":"Paillasse hospitali\u00e8re 5"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":18128,"menu_order":0,"template":"","format":"standard","meta":{"footnotes":""},"portfolio_category":[264],"portfolio_skills":[],"portfolio_tags":[],"class_list":["post-2709","avada_portfolio","type-avada_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-paillasse-hospitaliere-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paillasse hospitali\u00e8re 5 | Sidpa<\/title>\n<meta name=\"description\" content=\"laboratoire, paillasse de laboratoire, labo, lab, mobilier de labo, mobilier de laboratoire, meubles bahut, sorbonne, sidpa, servilab, sur mesure, labo sur mesure, laboratoire sur mesure, laboratoire sur mesure devis, laboratoire complet, meubles de laboratoire, \u00e9quipement de labo, \u00e9quipement de laboratoire, paillasse, meuble labo, chaise labo, paillasse scolaire, table labo, paillasse \u00e9cole, meuble laboratoire \u00e9cole, meuble labo \u00e9cole, agencement de laboratoire, agencement labo, paillasse PMR, hotte de laboratoire, hotte labo,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paillasse hospitali\u00e8re 5 | Sidpa\" \/>\n<meta property=\"og:description\" content=\"laboratoire, paillasse de laboratoire, labo, lab, mobilier de labo, mobilier de laboratoire, meubles bahut, sorbonne, sidpa, servilab, sur mesure, labo sur mesure, laboratoire sur mesure, laboratoire sur mesure devis, laboratoire complet, meubles de laboratoire, \u00e9quipement de labo, \u00e9quipement de laboratoire, paillasse, meuble labo, chaise labo, paillasse scolaire, table labo, paillasse \u00e9cole, meuble laboratoire \u00e9cole, meuble labo \u00e9cole, agencement de laboratoire, agencement labo, paillasse PMR, hotte de laboratoire, hotte labo,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5\" \/>\n<meta property=\"og:site_name\" content=\"Sidpa\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-16T15:38:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sidpa72.fr\/w\/wp-content\/uploads\/2014\/07\/img1-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5\",\"url\":\"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5\",\"name\":\"Paillasse hospitali\u00e8re 5 | Sidpa\",\"isPartOf\":{\"@id\":\"https:\/\/www.sidpa72.fr\/w\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sidpa72.fr\/w\/wp-content\/uploads\/2014\/07\/img1-8.jpg\",\"datePublished\":\"2014-07-02T14:17:57+00:00\",\"dateModified\":\"2019-12-16T15:38:14+00:00\",\"description\":\"laboratoire, paillasse de laboratoire, labo, lab, mobilier de labo, mobilier de laboratoire, meubles bahut, sorbonne, sidpa, servilab, sur mesure, labo sur mesure, laboratoire sur mesure, laboratoire sur mesure devis, laboratoire complet, meubles de laboratoire, \u00e9quipement de labo, \u00e9quipement de laboratoire, paillasse, meuble labo, chaise labo, paillasse scolaire, table labo, paillasse \u00e9cole, meuble laboratoire \u00e9cole, meuble labo \u00e9cole, agencement de laboratoire, agencement labo, paillasse PMR, hotte de laboratoire, hotte labo,\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5#primaryimage\",\"url\":\"https:\/\/www.sidpa72.fr\/w\/wp-content\/uploads\/2014\/07\/img1-8.jpg\",\"contentUrl\":\"https:\/\/www.sidpa72.fr\/w\/wp-content\/uploads\/2014\/07\/img1-8.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sidpa72.fr\/w\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\/\/www.sidpa72.fr\/w\/portfolio-items\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Paillasse hospitali\u00e8re 5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sidpa72.fr\/w\/#website\",\"url\":\"https:\/\/www.sidpa72.fr\/w\/\",\"name\":\"Sidpa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sidpa72.fr\/w\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paillasse hospitali\u00e8re 5 | Sidpa","description":"laboratoire, paillasse de laboratoire, labo, lab, mobilier de labo, mobilier de laboratoire, meubles bahut, sorbonne, sidpa, servilab, sur mesure, labo sur mesure, laboratoire sur mesure, laboratoire sur mesure devis, laboratoire complet, meubles de laboratoire, \u00e9quipement de labo, \u00e9quipement de laboratoire, paillasse, meuble labo, chaise labo, paillasse scolaire, table labo, paillasse \u00e9cole, meuble laboratoire \u00e9cole, meuble labo \u00e9cole, agencement de laboratoire, agencement labo, paillasse PMR, hotte de laboratoire, hotte labo,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5","og_locale":"en_US","og_type":"article","og_title":"Paillasse hospitali\u00e8re 5 | Sidpa","og_description":"laboratoire, paillasse de laboratoire, labo, lab, mobilier de labo, mobilier de laboratoire, meubles bahut, sorbonne, sidpa, servilab, sur mesure, labo sur mesure, laboratoire sur mesure, laboratoire sur mesure devis, laboratoire complet, meubles de laboratoire, \u00e9quipement de labo, \u00e9quipement de laboratoire, paillasse, meuble labo, chaise labo, paillasse scolaire, table labo, paillasse \u00e9cole, meuble laboratoire \u00e9cole, meuble labo \u00e9cole, agencement de laboratoire, agencement labo, paillasse PMR, hotte de laboratoire, hotte labo,","og_url":"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5","og_site_name":"Sidpa","article_modified_time":"2019-12-16T15:38:14+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.sidpa72.fr\/w\/wp-content\/uploads\/2014\/07\/img1-8.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5","url":"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5","name":"Paillasse hospitali\u00e8re 5 | Sidpa","isPartOf":{"@id":"https:\/\/www.sidpa72.fr\/w\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5#primaryimage"},"image":{"@id":"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5#primaryimage"},"thumbnailUrl":"https:\/\/www.sidpa72.fr\/w\/wp-content\/uploads\/2014\/07\/img1-8.jpg","datePublished":"2014-07-02T14:17:57+00:00","dateModified":"2019-12-16T15:38:14+00:00","description":"laboratoire, paillasse de laboratoire, labo, lab, mobilier de labo, mobilier de laboratoire, meubles bahut, sorbonne, sidpa, servilab, sur mesure, labo sur mesure, laboratoire sur mesure, laboratoire sur mesure devis, laboratoire complet, meubles de laboratoire, \u00e9quipement de labo, \u00e9quipement de laboratoire, paillasse, meuble labo, chaise labo, paillasse scolaire, table labo, paillasse \u00e9cole, meuble laboratoire \u00e9cole, meuble labo \u00e9cole, agencement de laboratoire, agencement labo, paillasse PMR, hotte de laboratoire, hotte labo,","breadcrumb":{"@id":"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5#primaryimage","url":"https:\/\/www.sidpa72.fr\/w\/wp-content\/uploads\/2014\/07\/img1-8.jpg","contentUrl":"https:\/\/www.sidpa72.fr\/w\/wp-content\/uploads\/2014\/07\/img1-8.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.sidpa72.fr\/w\/en\/portfolio-items\/paillasse-hospitaliere-5#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sidpa72.fr\/w\/en"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/www.sidpa72.fr\/w\/portfolio-items"},{"@type":"ListItem","position":3,"name":"Paillasse hospitali\u00e8re 5"}]},{"@type":"WebSite","@id":"https:\/\/www.sidpa72.fr\/w\/#website","url":"https:\/\/www.sidpa72.fr\/w\/","name":"Sidpa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sidpa72.fr\/w\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.sidpa72.fr\/w\/en\/wp-json\/wp\/v2\/avada_portfolio\/2709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sidpa72.fr\/w\/en\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/www.sidpa72.fr\/w\/en\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.sidpa72.fr\/w\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.sidpa72.fr\/w\/en\/wp-json\/wp\/v2\/avada_portfolio\/2709\/revisions"}],"predecessor-version":[{"id":17875,"href":"https:\/\/www.sidpa72.fr\/w\/en\/wp-json\/wp\/v2\/avada_portfolio\/2709\/revisions\/17875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sidpa72.fr\/w\/en\/wp-json\/wp\/v2\/media\/18128"}],"wp:attachment":[{"href":"https:\/\/www.sidpa72.fr\/w\/en\/wp-json\/wp\/v2\/media?parent=2709"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/www.sidpa72.fr\/w\/en\/wp-json\/wp\/v2\/portfolio_category?post=2709"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/www.sidpa72.fr\/w\/en\/wp-json\/wp\/v2\/portfolio_skills?post=2709"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/www.sidpa72.fr\/w\/en\/wp-json\/wp\/v2\/portfolio_tags?post=2709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}